{"id":324,"count":32,"description":"","link":"https:\/\/pecpets.com\/es\/product-category\/pet-accessory\/","name":"Accesorios para mascotas","slug":"pet-accessory","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/pecpets.com\/es\/wp-json\/wp\/v2\/product_cat\/324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pecpets.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/pecpets.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/pecpets.com\/es\/wp-json\/wp\/v2\/product?product_cat=324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}